{"id":670,"date":"2019-03-27T10:27:33","date_gmt":"2019-03-27T09:27:33","guid":{"rendered":"https:\/\/www.naturella.chproduit\/reichhaltige-creme\/"},"modified":"2026-07-10T15:17:27","modified_gmt":"2026-07-10T13:17:27","slug":"reichhaltige-creme-fur-das-gesicht","status":"publish","type":"product","link":"https:\/\/www.naturella.ch\/de\/produkt\/reichhaltige-creme-fur-das-gesicht\/","title":{"rendered":"Reichhaltige Creme f\u00fcr das Gesicht"},"content":{"rendered":"<p>K\u00e4lte, Schmutz, Wind, Temparaturschwankungen und selbstverst\u00e4ndlich die vergehenden Jahre sind Feinde f\u00fcr die Gesichtshaut. Zart und empfindlich, ist sie verletzlicher als die K\u00f6rperhaut und verdient Ihre volle Aufmerksamkeit mit einer besonderen Pflege.<\/p>\n<p>Das Gespann Argan\u00f6l + Aloe Vera liefert genau das, was sie ben\u00f6tigt\u2009: wertvolle Ern\u00e4hrung, Tiefenbefeuchtung und wirkungsvollen Schutz gegen die verschiedenen Agressionen und gleichzeitig die bestm\u00f6gliche Milderung der Alterungsspuren. Zusammen sind sie Champions, wenn es um die Erhaltung von Frische, Spannkraft und Sch\u00f6nheit geht. Ob zarte, trockene, junge oder reife Haut, alle Hauttypen werden davon begeistert sein !<\/p>\n<p>Jeden Morgen mit den Fingerspitzen auftragen, ebenso am Abend als Nachtcreme, um die ausgehungerte Haut zu verw\u00f6hnen.<\/p>\n","protected":false},"excerpt":{"rendered":"<h5>Ultraschutz f\u00fcr das Gesicht<\/h5>\n<h3>Aloe Vera + Argan\u00f6l\u2009:<br \/>\ndas Supergespannle<\/h3>\n<p>Sehr n\u00e4hrend, befeuchtet diese reichhaltige Creme f\u00fcr das Gesicht die Oberfl\u00e4chenschichten der Haut und sch\u00fctzt sie, dank ihrer Wirkstoffe vor Verschmutzungen und den Gefahren der Zeit.<\/p>\n","protected":false},"featured_media":12113,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"powered_cache_disable_cache":false,"powered_cache_disable_lazyload":false,"powered_cache_disable_css_optimization":false,"powered_cache_disable_js_optimization":false},"product_brand":[],"product_cat":[58],"product_tag":[104],"class_list":{"0":"post-670","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kosmetik-schonheit","7":"product_tag-provence-de","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Reichhaltige Creme f\u00fcr das Gesicht | Schweiz | 50 ml - Naturella Diffusion SA<\/title>\n<meta name=\"description\" content=\"Vorr\u00e4tig | \u2605\u2605\u2605 Hergestellt in der Provence \u2605\u2605 Diese reichhaltige Gesichtscreme ist sehr n\u00e4hrend und versorgt die obersten Hautschichten mit Feuchtigkeit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.naturella.ch\/de\/produkt\/reichhaltige-creme-fur-das-gesicht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reichhaltige Creme f\u00fcr das Gesicht\" \/>\n<meta property=\"og:description\" content=\"Vorr\u00e4tig | \u2605\u2605\u2605 Hergestellt in der Provence \u2605\u2605 Diese reichhaltige Gesichtscreme ist sehr n\u00e4hrend und versorgt die obersten Hautschichten mit Feuchtigkeit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.naturella.ch\/de\/produkt\/reichhaltige-creme-fur-das-gesicht\/\" \/>\n<meta property=\"og:site_name\" content=\"Naturella\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Naturella-Diffusion-102844258398231\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T13:17:27+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.naturella.ch\/wp-content\/uploads\/2019\/03\/Creme-riche-PNG.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1020\" \/>\n\t<meta property=\"og:image:height\" content=\"1020\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Preis\" \/>\n\t<meta name=\"twitter:data1\" content=\"&#067;&#072;&#070;&nbsp;24.00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Verf\u00fcgbarkeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"Auf Lager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.naturella.ch\\\/de\\\/produkt\\\/reichhaltige-creme-fur-das-gesicht\\\/\",\"url\":\"https:\\\/\\\/www.naturella.ch\\\/de\\\/produkt\\\/reichhaltige-creme-fur-das-gesicht\\\/\",\"name\":\"Reichhaltige Creme f\u00fcr das Gesicht | Schweiz | 50 ml - Naturella Diffusion SA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naturella.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.naturella.ch\\\/de\\\/produkt\\\/reichhaltige-creme-fur-das-gesicht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naturella.ch\\\/de\\\/produkt\\\/reichhaltige-creme-fur-das-gesicht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.naturella.ch\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Creme-riche-PNG.png\",\"datePublished\":\"2019-03-27T09:27:33+00:00\",\"dateModified\":\"2026-07-10T13:17:27+00:00\",\"description\":\"Vorr\u00e4tig | \u2605\u2605\u2605 Hergestellt in der Provence \u2605\u2605 Diese reichhaltige Gesichtscreme ist sehr n\u00e4hrend und versorgt die obersten Hautschichten mit Feuchtigkeit.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.naturella.ch\\\/de\\\/produkt\\\/reichhaltige-creme-fur-das-gesicht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.naturella.ch\\\/de\\\/produkt\\\/reichhaltige-creme-fur-das-gesicht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.naturella.ch\\\/de\\\/produkt\\\/reichhaltige-creme-fur-das-gesicht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.naturella.ch\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Creme-riche-PNG.png\",\"contentUrl\":\"https:\\\/\\\/www.naturella.ch\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/Creme-riche-PNG.png\",\"width\":1020,\"height\":1020,\"caption\":\"Cr\u00e8me riche\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.naturella.ch\\\/de\\\/produkt\\\/reichhaltige-creme-fur-das-gesicht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.naturella.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online-Shop\",\"item\":\"https:\\\/\\\/www.naturella.ch\\\/de\\\/online-shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Reichhaltige Creme f\u00fcr das Gesicht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.naturella.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.naturella.ch\\\/de\\\/\",\"name\":\"Naturella\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.naturella.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.naturella.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.naturella.ch\\\/de\\\/#organization\",\"name\":\"Naturella Diffusion SA\",\"url\":\"https:\\\/\\\/www.naturella.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.naturella.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.naturella.ch\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Logo-Naturella_2021_RVB-e1619530233334.png\",\"contentUrl\":\"https:\\\/\\\/www.naturella.ch\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Logo-Naturella_2021_RVB-e1619530233334.png\",\"width\":340,\"height\":170,\"caption\":\"Naturella Diffusion SA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naturella.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Naturella-Diffusion-102844258398231\",\"https:\\\/\\\/www.instagram.com\\\/naturella_diffusion\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/www.naturella.ch\\\/remboursements_retours\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"24.00\" \/>\n<meta property=\"product:price:currency\" content=\"CHF\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"3022\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Reichhaltige Creme f\u00fcr das Gesicht | Schweiz | 50 ml - Naturella Diffusion SA","description":"Vorr\u00e4tig | \u2605\u2605\u2605 Hergestellt in der Provence \u2605\u2605 Diese reichhaltige Gesichtscreme ist sehr n\u00e4hrend und versorgt die obersten Hautschichten mit Feuchtigkeit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.naturella.ch\/de\/produkt\/reichhaltige-creme-fur-das-gesicht\/","og_locale":"de_DE","og_type":"article","og_title":"Reichhaltige Creme f\u00fcr das Gesicht","og_description":"Vorr\u00e4tig | \u2605\u2605\u2605 Hergestellt in der Provence \u2605\u2605 Diese reichhaltige Gesichtscreme ist sehr n\u00e4hrend und versorgt die obersten Hautschichten mit Feuchtigkeit.","og_url":"https:\/\/www.naturella.ch\/de\/produkt\/reichhaltige-creme-fur-das-gesicht\/","og_site_name":"Naturella","article_publisher":"https:\/\/www.facebook.com\/Naturella-Diffusion-102844258398231","article_modified_time":"2026-07-10T13:17:27+00:00","og_image":[{"width":1020,"height":1020,"url":"http:\/\/www.naturella.ch\/wp-content\/uploads\/2019\/03\/Creme-riche-PNG.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Preis":"&#67;&#72;&#70;&nbsp;24.00","Verf\u00fcgbarkeit":"Auf Lager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.naturella.ch\/de\/produkt\/reichhaltige-creme-fur-das-gesicht\/","url":"https:\/\/www.naturella.ch\/de\/produkt\/reichhaltige-creme-fur-das-gesicht\/","name":"Reichhaltige Creme f\u00fcr das Gesicht | Schweiz | 50 ml - Naturella Diffusion SA","isPartOf":{"@id":"https:\/\/www.naturella.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.naturella.ch\/de\/produkt\/reichhaltige-creme-fur-das-gesicht\/#primaryimage"},"image":{"@id":"https:\/\/www.naturella.ch\/de\/produkt\/reichhaltige-creme-fur-das-gesicht\/#primaryimage"},"thumbnailUrl":"https:\/\/www.naturella.ch\/wp-content\/uploads\/2019\/03\/Creme-riche-PNG.png","datePublished":"2019-03-27T09:27:33+00:00","dateModified":"2026-07-10T13:17:27+00:00","description":"Vorr\u00e4tig | \u2605\u2605\u2605 Hergestellt in der Provence \u2605\u2605 Diese reichhaltige Gesichtscreme ist sehr n\u00e4hrend und versorgt die obersten Hautschichten mit Feuchtigkeit.","breadcrumb":{"@id":"https:\/\/www.naturella.ch\/de\/produkt\/reichhaltige-creme-fur-das-gesicht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.naturella.ch\/de\/produkt\/reichhaltige-creme-fur-das-gesicht\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.naturella.ch\/de\/produkt\/reichhaltige-creme-fur-das-gesicht\/#primaryimage","url":"https:\/\/www.naturella.ch\/wp-content\/uploads\/2019\/03\/Creme-riche-PNG.png","contentUrl":"https:\/\/www.naturella.ch\/wp-content\/uploads\/2019\/03\/Creme-riche-PNG.png","width":1020,"height":1020,"caption":"Cr\u00e8me riche"},{"@type":"BreadcrumbList","@id":"https:\/\/www.naturella.ch\/de\/produkt\/reichhaltige-creme-fur-das-gesicht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.naturella.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Online-Shop","item":"https:\/\/www.naturella.ch\/de\/online-shop\/"},{"@type":"ListItem","position":3,"name":"Reichhaltige Creme f\u00fcr das Gesicht"}]},{"@type":"WebSite","@id":"https:\/\/www.naturella.ch\/de\/#website","url":"https:\/\/www.naturella.ch\/de\/","name":"Naturella","description":"","publisher":{"@id":"https:\/\/www.naturella.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.naturella.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.naturella.ch\/de\/#organization","name":"Naturella Diffusion SA","url":"https:\/\/www.naturella.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.naturella.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.naturella.ch\/wp-content\/uploads\/2021\/04\/Logo-Naturella_2021_RVB-e1619530233334.png","contentUrl":"https:\/\/www.naturella.ch\/wp-content\/uploads\/2021\/04\/Logo-Naturella_2021_RVB-e1619530233334.png","width":340,"height":170,"caption":"Naturella Diffusion SA"},"image":{"@id":"https:\/\/www.naturella.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Naturella-Diffusion-102844258398231","https:\/\/www.instagram.com\/naturella_diffusion\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/www.naturella.ch\/remboursements_retours\/"}}]},"product_price_amount":"24.00","product_price_currency":"CHF","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"3022","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.naturella.ch\/de\/wp-json\/wp\/v2\/product\/670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naturella.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.naturella.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.naturella.ch\/de\/wp-json\/wp\/v2\/comments?post=670"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.naturella.ch\/de\/wp-json\/wp\/v2\/media\/12113"}],"wp:attachment":[{"href":"https:\/\/www.naturella.ch\/de\/wp-json\/wp\/v2\/media?parent=670"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.naturella.ch\/de\/wp-json\/wp\/v2\/product_brand?post=670"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.naturella.ch\/de\/wp-json\/wp\/v2\/product_cat?post=670"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.naturella.ch\/de\/wp-json\/wp\/v2\/product_tag?post=670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}